{"id":7622,"date":"2023-03-28T07:57:12","date_gmt":"2023-03-28T07:57:12","guid":{"rendered":"https:\/\/iav-online.de\/datenschutz\/"},"modified":"2025-02-14T08:57:37","modified_gmt":"2025-02-14T08:57:37","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/iav-online.de\/en\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1686147074705{margin-top: 50px !important;padding-top: 40px !important;}&#8221;][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3>Einleitung<\/h3>\n<p>Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie insbesondere entsprechend Art. 13 und Art. 14 Datenschutz-Grundverordnung (DSGVO) dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als &#8220;Daten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, in mobilen Applikationen sowie innerhalb externer Onlinepr\u00e4senzen.<\/p>\n<p>Zur Verbesserung der Lesbarkeit dieser Erkl\u00e4rung verwenden wir im Regelfall die m\u00e4nnliche Begriffsversion, umfasst sind jedoch alle betroffenen Personen (m\/w\/d).<\/p>\n<p>Stand: 14.02.2025[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Inhalts\u00fcbersicht<\/h3>\n<ul class=\"index\">\n<li><a href=\"#Verantwortlicher\">Verantwortlicher<\/a><\/li>\n<li><a href=\"#Kontakt Datenschutzbeauftragter\">Kontakt Datenschutzbeauftragter<\/a><\/li>\n<li><a href=\"#\u00dcbersicht der Verarbeitungen\">\u00dcbersicht der Verarbeitungen<\/a><\/li>\n<li><a href=\"#\u00dcbermittlung und Offenbarung von personenbezogenen Daten\">\u00dcbermittlung und Offenbarung von personenbezogenen Daten<\/a><\/li>\n<li><a href=\"#Datenverarbeitung in Drittl\u00e4ndern\">Datenverarbeitung in Drittl\u00e4ndern<\/a><\/li>\n<li><a href=\"#Sicherheitsma\u00dfnahmen\">Sicherheitsma\u00dfnahmen<\/a><\/li>\n<li><a href=\"#Einsatz von Cookies\">Einsatz von Cookies<\/a><\/li>\n<li><a href=\"#Vimeo\">Vimeo<\/a><\/li>\n<li><a href=\"#Calendly\">Calendly<\/a><\/li>\n<li><a href=\"#Wahrnehmung von Aufgaben nach Satzung oder Gesch\u00e4ftsordnung\">Wahrnehmung von Aufgaben nach Satzung oder Gesch\u00e4ftsordnung<\/a><\/li>\n<li><a href=\"#(Online-)Veranstaltungen und Seminare\">(Online-)Veranstaltungen und Seminare<\/a><\/li>\n<li><a href=\"#Rechtsberatung und Prozessvertretung\">Rechtsberatung und Prozessvertretung<\/a><\/li>\n<li><a href=\"#Datenschutzmanagement\">Datenschutzmanagement<\/a><\/li>\n<li><a href=\"#Registrierung und Anmeldung\">Registrierung und Anmeldung<\/a><\/li>\n<li><a href=\"#Kontaktaufnahme\">Kontaktaufnahme<\/a><\/li>\n<li><a href=\"#Bereitstellung des Onlineangebotes und Webhosting\">Bereitstellung des Onlineangebotes und Webhosting<\/a><\/li>\n<li><a href=\"#Bewerbungsverfahren und Personaladministration\">Bewerbungsverfahren und Personaladministration<\/a><\/li>\n<li><a href=\"#Newsletter und Breitenkommunikation\">Newsletter und Breitenkommunikation<\/a><\/li>\n<li><a href=\"#Akquise\">Akquise<\/a><\/li>\n<li><a href=\"#UmfrageOnline\">UmfrageOnline<\/a><\/li>\n<li><a href=\"#L\u00f6schung von Daten\">L\u00f6schung von Daten<\/a><\/li>\n<li><a href=\"#\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung\">\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/a><\/li>\n<li><a href=\"#Rechte der betroffenen Personen\">Rechte der betroffenen Personen<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Verantwortlicher&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m3\">Verantwortlicher<\/h3>\n<p>Industrieller Arbeitgeberverband Osnabr\u00fcck &#8211; Emsland &#8211; Grafschaft Bentheim e.V.<br \/>\nBohmter Stra\u00dfe 11, 49074 Osnabr\u00fcck<br \/>\nVereinsregister des Amtsgerichts Osnabr\u00fcck: VR 1116<\/p>\n<p><strong>Vertretungsberechtigte Personen:<\/strong><br \/>\nVorstandsvorsitzender: Olaf Piepenbrock; Hauptgesch\u00e4ftsf\u00fchrerin: Jasmin Markhof<\/p>\n<p><strong>E-Mail-Adresse:<\/strong> <a href=\"mailto:info@iav-online.de\" target=\"_blank\" rel=\"noopener\">info@iav-online.de<\/a><\/p>\n<p><strong>Telefon:<\/strong> 0541\/77068-0<\/p>\n<p><strong>Impressum:<\/strong> <a href=\"https:\/\/iav-online.de\/impressum\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.iav-online.de\/impressum<\/a><\/p>\n<p>Ggf. gemeinsam mit diesem Verantwortlichen:<\/p>\n<p>NiedersachsenMetall \u2013 Verband der Metallindustriellen Niedersachsens e.V.,<br \/>\nBezirksgruppe Osnabr\u00fcck &#8211; Emsland &#8211; Grafschaft &#8211; Bentheim<\/p>\n<p>Bohmter Stra\u00dfe 11, 49074 Osnabr\u00fcck,<br \/>\nTel: 0541\/77068-0, Email: <a href=\"mailto:info@niedersachsenmetall.de\" target=\"_blank\" rel=\"noopener\">info@niedersachsenmetall.de<\/a>,<br \/>\n<a href=\"https:\/\/www.niedersachsenmetall.de\/osnabrueck-emsland-grafschaft-bentheim\" target=\"_blank\" rel=\"noopener\">https:\/\/www.niedersachsenmetall.de\/osnabrueck-emsland-grafschaft-bentheim<\/a><\/p>\n<p>Ggf. gemeinsam mit diesem Verantwortlichen:<\/p>\n<p>VME-Stiftung Osnabr\u00fcck-Emsland<\/p>\n<p>Bohmter Stra\u00dfe 11, 49074 Osnabr\u00fcck,<br \/>\nTel: 0541\/77068-0, Email: <a href=\"mailto:info@vme-stiftung.de\" target=\"_blank\" rel=\"noopener\">info@vme-stiftung.de<\/a>,<br \/>\n<a href=\"https:\/\/www.vme-stiftung.de\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.vme-stiftung.de\/<\/a><\/p>\n<p>Der Industrielle Arbeitgeberverband Osnabr\u00fcck &#8211; Emsland &#8211; Grafschaft Bentheim e.V., die NiedersachsenMetall Bezirksgruppe Osnabr\u00fcck &#8211; Emsland &#8211; Grafschaft &#8211; Bentheim und die VME-Stiftung Osnabr\u00fcck-Emsland werden nachfolgend gemeinsam als Verb\u00e4ndegemeinschaft bezeichnet.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Kontakt Datenschutzbeauftragter&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m11\">Kontakt Datenschutzbeauftragter<\/h3>\n<p><a href=\"mailto:datenschutz@iav-online.de\" target=\"_blank\" rel=\"noopener\">datenschutz@iav-online.de<\/a><br \/>\nc\/o Scope &amp; Focus Service-Gesellschaft mbH<br \/>\nLeonhardstra\u00dfe 2, 30175 Hannover<br \/>\nTel: 0511\/3642210[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;\u00dcbersicht der Verarbeitungen&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"mOverview\">\u00dcbersicht der Verarbeitungen<\/h3>\n<p>Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h4>Arten der verarbeiteten Daten<\/h4>\n<ul>\n<li>Bestandsdaten (z.B. Namen, Adressen)<\/li>\n<li>Bewerberdaten (z.B. Angaben zur Person, Post- und Kontaktadressen, die zur Bewerbung geh\u00f6renden Unterlagen und die darin enthaltenen Informationen, wie z.B. Anschreiben, Lebenslauf, Zeugnisse sowie weitere im Hinblick auf eine konkrete Stelle oder freiwillig von Bewerbern mitgeteilte Informationen zu deren Person oder Qualifikation)<\/li>\n<li>Personaldaten (z.B. Angaben zur Person, Post- und Kontaktadressen, Sozialdaten, Vertrags- und Gehaltsdaten)<\/li>\n<li>Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos)<\/li>\n<li>Kontaktdaten (z.B. E-Mail, Telefonnummern)<\/li>\n<li>Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen)<\/li>\n<li>Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten)<\/li>\n<li>Informationen, die f\u00fcr die Geltendmachung und Verteidigung von Rechten im Rahmen der Rechtsberatung notwendig sind (z.B. Sachverhaltsdaten, Sozialdaten)<\/li>\n<li>Vertragsdaten (z.B. Vertragsgegenstand, Laufzeit)<\/li>\n<li>Zahlungsdaten (z.B. Bankverbindungen, Rechnungen, Zahlungshistorie)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h4>Kategorien betroffener Personen<\/h4>\n<ul>\n<li>Bewerber<\/li>\n<li>Besch\u00e4ftigte<\/li>\n<li>Mitglieder, Organe und Besch\u00e4ftigte von Mitgliedern<\/li>\n<li>Gesch\u00e4fts- und Vertragspartner<\/li>\n<li>Teilnehmer (z.B. Veranstaltungen und Seminare)<\/li>\n<li>Interessenten<\/li>\n<li>Kommunikationspartner<\/li>\n<li>Verfahrensbeteiligte (auch z.B. Mitarbeiter von Gerichten und Beh\u00f6rden)<\/li>\n<li>Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h4>Zwecke der Verarbeitung<\/h4>\n<ul>\n<li>Bewerbungsverfahren &amp; Personaladministration (Begr\u00fcndung und etwaige sp\u00e4tere Durchf\u00fchrung sowie m\u00f6gliche sp\u00e4tere Beendigung des Besch\u00e4ftigungsverh\u00e4ltnisses.)<\/li>\n<li>Vertragliche Leistungen und Service<\/li>\n<li>Verwaltung und Beantwortung von Anfragen<\/li>\n<li>Rechtsberatung und Prozessvertretung<\/li>\n<li>(Online-) Veranstaltungen und Seminare<\/li>\n<li>Datenschutzmanagement<\/li>\n<li>Direktmarketing (z.B. per E-Mail oder postalisch)<\/li>\n<li>Interessenbasiertes und verhaltensbezogenes Marketing<\/li>\n<li>Kontaktanfragen und Kommunikation<\/li>\n<li>EDV-Administration<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h4 id=\"m13\">Ma\u00dfgebliche Rechtsgrundlagen<\/h4>\n<p>Im Folgenden teilen wir die Rechtsgrundlagen der Datenschutzgrundverordnung (DSGVO), auf deren Basis wir die personenbezogenen Daten verarbeiten, mit. Bitte beachten Sie, dass zus\u00e4tzlich zu den Regelungen der DSGVO die nationalen Datenschutzvorgaben in Ihrem bzw. unserem Wohn- und Sitzland gelten k\u00f6nnen.<\/p>\n<ul>\n<li><strong>Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO):<\/strong> Die betroffene Person hat ihre Einwilligung in die Verarbeitung der sie betreffenden personenbezogenen Daten f\u00fcr einen spezifischen Zweck oder mehrere bestimmte Zwecke gegeben.<\/li>\n<li><strong>Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO):<\/strong> Die Verarbeitung ist f\u00fcr die Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, die auf Anfrage der betroffenen Person erfolgen.<\/li>\n<li><strong>Rechtliche Verpflichtung (Art. 6 Abs. 1 S. 1 lit. c. DSGVO):<\/strong> Die Verarbeitung ist zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich, der der Verantwortliche unterliegt.<\/li>\n<li><strong>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO):<\/strong> Die Verarbeitung ist zur Wahrung der berechtigten Interessen des Verantwortlichen oder eines Dritten erforderlich, sofern nicht die Interessen oder Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz personenbezogener Daten erfordern, \u00fcberwiegen.<\/li>\n<\/ul>\n<p><strong>Nationale Datenschutzregelungen in Deutschland:<\/strong> Zus\u00e4tzlich zu den Datenschutzregelungen der DSGVO gelten nationale Regelungen zum Datenschutz in Deutschland. Hierzu geh\u00f6rt insbesondere das Gesetz zum Schutz vor Missbrauch personenbezogener Daten bei der Datenverarbeitung (Bundesdatenschutzgesetz \u2013 BDSG). Das BDSG enth\u00e4lt insbesondere Spezialregelungen zum Recht auf Auskunft, zum Recht auf L\u00f6schung, zum Widerspruchsrecht, zur Verarbeitung besonderer Kategorien personenbezogener Daten, zur Verarbeitung f\u00fcr andere Zwecke und zur \u00dcbermittlung sowie automatisierten Entscheidungsfindung im Einzelfall einschlie\u00dflich Profiling. Des Weiteren regelt es die Datenverarbeitung f\u00fcr Zwecke des Besch\u00e4ftigungsverh\u00e4ltnisses (\u00a7 26 BDSG), insbesondere im Hinblick auf die Begr\u00fcndung, Durchf\u00fchrung oder Beendigung von Besch\u00e4ftigungsverh\u00e4ltnissen sowie die Einwilligung von Besch\u00e4ftigten. Ferner k\u00f6nnen Landesdatenschutzgesetze der einzelnen Bundesl\u00e4nder zur Anwendung gelangen.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;\u00dcbermittlung und Offenbarung von personenbezogenen Daten&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m25\">\u00dcbermittlung und Offenbarung von personenbezogenen Daten<\/h3>\n<p>Im Rahmen unserer Verarbeitung von personenbezogenen Daten kommt es vor, dass die Daten an andere Stellen, Unternehmen, rechtlich selbstst\u00e4ndige Organisationseinheiten oder Personen \u00fcbermittelt oder sie ihnen gegen\u00fcber offengelegt werden. Zu den Empf\u00e4ngern dieser Daten k\u00f6nnen z.B. Zahlungsinstitute im Rahmen von Zahlungsvorg\u00e4ngen, mit IT-Aufgaben beauftragte Dienstleister oder Anbieter von Diensten und Inhalten, die in eine Webseite eingebunden werden, geh\u00f6ren. In solchen Fall beachten wir die gesetzlichen Vorgaben und schlie\u00dfen insbesondere entsprechende Vertr\u00e4ge bzw. Vereinbarungen, die dem Schutz Ihrer Daten dienen, mit den Empf\u00e4ngern Ihrer Daten ab.<\/p>\n<p><strong>Daten\u00fcbermittlung innerhalb der Verb\u00e4ndegemeinschaft:<\/strong> Wir k\u00f6nnen personenbezogene Daten an andere Organisationen innerhalb unserer Verb\u00e4ndegemeinschaft \u00fcbermitteln oder ihnen den Zugriff auf diese Daten gew\u00e4hren. Sofern diese Weitergabe zu administrativen Zwecken erfolgt, beruht die Weitergabe der Daten auf unseren berechtigten unternehmerischen und betriebswirtschaftlichen Interessen oder erfolgt, sofern sie zur Erf\u00fcllung unserer vertragsbezogenen Verpflichtungen erforderlich ist oder wenn eine Einwilligung der Betroffenen oder eine gesetzliche Erlaubnis vorliegt.<\/p>\n<p><strong>Daten\u00fcbermittlung innerhalb der Organisation:<\/strong> Wir k\u00f6nnen personenbezogene Daten an andere Stellen innerhalb unserer Organisation \u00fcbermitteln oder ihnen den Zugriff auf diese Daten gew\u00e4hren. Sofern diese Weitergabe zu administrativen Zwecken erfolgt, beruht die Weitergabe der Daten auf unseren berechtigten unternehmerischen und betriebswirtschaftlichen Interessen oder erfolgt, sofern sie Erf\u00fcllung unserer vertragsbezogenen Verpflichtungen erforderlich ist oder wenn eine Einwilligung der Betroffenen oder eine gesetzliche Erlaubnis vorliegt.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Datenverarbeitung in Drittl\u00e4ndern&#8221;][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 id=\"m24\">Datenverarbeitung in Drittl\u00e4ndern<\/h3>\n<p>Sofern wir Daten in einem Drittland (d. h., au\u00dferhalb der Europ\u00e4ischen Union (EU), des Europ\u00e4ischen Wirtschaftsraums (EWR)) verarbeiten oder die Verarbeitung im Rahmen der Inanspruchnahme von Diensten Dritter oder der Offenlegung bzw. \u00dcbermittlung von Daten an andere Personen, Stellen oder Unternehmen stattfindet, erfolgt dies nur im Einklang mit den gesetzlichen Vorgaben. Sofern das Datenschutzniveau in dem Drittland mittels eines Angemessenheitsbeschlusses anerkannt wurde (Art. 45 DSGVO), dient dieser als Grundlage des Datentransfers. Im \u00dcbrigen erfolgen Datentransfers nur dann, wenn das Datenschutzniveau anderweitig gesichert ist, insbesondere durch Standardvertragsklauseln (Art. 46 Abs. 2 lit. c) DSGVO), ausdr\u00fcckliche Einwilligung oder im Fall vertraglicher oder gesetzlich erforderlicher \u00dcbermittlung (Art. 49 Abs. 1 DSGVO). Im \u00dcbrigen teilen wir Ihnen die Grundlagen der Drittland\u00fcbermittlung bei den einzelnen Anbietern aus dem Drittland mit, wobei die Angemessenheitsbeschl\u00fcsse als Grundlagen vorrangig gelten. Informationen zu Drittlandtransfers und vorliegenden Angemessenheitsbeschl\u00fcssen k\u00f6nnen dem Informationsangebot der EU-Kommission entnommen werden:\u00a0<a href=\"https:\/\/commission.europa.eu\/law\/law-topic\/data-protection\/international-dimension-data-protection_en?prefLang=de\" target=\"_blank\" rel=\"noopener\">https:\/\/commission.europa.eu\/law\/law-topic\/data-protection\/international-dimension-data-protection_en?prefLang=de.<\/a>\u00a0Im Rahmen des sogenannten \u201eData Privacy Framework&#8221; (DPF) hat die EU-Kommission das Datenschutzniveau ebenfalls f\u00fcr bestimmte Unternehmen aus den USA im Rahmen der Angemessenheitsbeschlusses vom 10.07.2023 als sicher anerkannt. Die Liste der zertifizierten Unternehmen als auch weitere Informationen zu dem DPF k\u00f6nnen Sie der Website des Handelsministeriums der USA unter\u00a0<a href=\"https:\/\/www.dataprivacyframework.gov\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.dataprivacyframework.gov\/<\/a> (in Englisch) entnehmen. Wir informieren Sie im Rahmen der Datenschutzhinweise, welche von uns eingesetzten Diensteanbieter unter dem Data Privacy Framework zertifiziert sind.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Sicherheitsma\u00dfnahmen&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m891\">Sicherheitsma\u00dfnahmen<\/h3>\n<p>Wir treffen nach Ma\u00dfgabe der gesetzlichen Vorgaben unter Ber\u00fccksichtigung des Stands der Technik, der Implementierungskosten und der Art, des Umfangs, der Umst\u00e4nde und der Zwecke der Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\u00dfes der Bedrohung der Rechte und Freiheiten nat\u00fcrlicher Personen geeignete technische und organisatorische Ma\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\u00e4hrleisten.<\/p>\n<p>Zu den Ma\u00dfnahmen geh\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\u00e4t und Verf\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\u00fcgbarkeit und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von Betroffenenrechten, die L\u00f6schung von Daten und Reaktionen auf die Gef\u00e4hrdung der Daten gew\u00e4hrleisten. Ferner ber\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.<\/p>\n<p><strong>SSL-Verschl\u00fcsselung (https):<\/strong> Um Ihre via unserem Online-Angebot \u00fcbermittelten Daten zu sch\u00fctzen, nutzen wir eine SSL-Verschl\u00fcsselung. Sie erkennen derart verschl\u00fcsselte Verbindungen an dem Pr\u00e4fix https:\/\/ in der Adresszeile Ihres Browsers.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Einsatz von Cookies&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m134\">Einsatz von Cookies<\/h3>\n<p><span class=\"code-example\"><a class=\"_brlbs-btn-cookie-preference borlabs-cookie-preference\" href=\"https:\/\/iav-online.de\/datenschutz\/#\">Cookie-Auswahl \u00e4ndern<\/a><\/span><\/p>\n<p>Cookies sind Textdateien, die Daten von besuchten Websites oder Domains enthalten und von einem Browser auf dem Computer des Benutzers gespeichert werden. Ein Cookie dient in erster Linie dazu, die Informationen \u00fcber einen Benutzer w\u00e4hrend oder nach seinem Besuch innerhalb eines Onlineangebotes zu speichern. Zu den gespeicherten Angaben k\u00f6nnen z.B. die Spracheinstellungen auf einer Webseite, der Loginstatus, ein Warenkorb oder die Stelle, an der ein Video geschaut wurde, geh\u00f6ren. Zu dem Begriff der Cookies z\u00e4hlen wir ferner andere Technologien, die die gleichen Funktionen wie Cookies erf\u00fcllen (z.B., wenn Angaben der Nutzer anhand pseudonymer Onlinekennzeichnungen gespeichert werden, auch als &#8220;Nutzer-IDs&#8221; bezeichnet)<\/p>\n<p><strong>Die folgenden Cookie-Typen und Funktionen werden unterschieden:<\/strong><\/p>\n<ul>\n<li><strong>Tempor\u00e4re Cookies (auch: Session- oder Sitzungs-Cookies):<\/strong>\u00a0Tempor\u00e4re Cookies werden sp\u00e4testens gel\u00f6scht, nachdem ein Nutzer ein Online-Angebot verlassen und seinen Browser geschlossen hat.<\/li>\n<li><strong>Permanente Cookies:<\/strong>\u00a0Permanente Cookies bleiben auch nach dem Schlie\u00dfen des Browsers gespeichert. So kann beispielsweise der Login-Status gespeichert oder bevorzugte Inhalte direkt angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\u00f6nnen die Interessen von Nutzern, die zur Reichweitenmessung oder zu Marketingzwecken verwendet werden, in einem solchen Cookie gespeichert werden.<\/li>\n<li><strong>First-Party-Cookies:<\/strong>\u00a0First-Party-Cookies werden von uns selbst gesetzt.<\/li>\n<li><strong>Third-Party-Cookies (auch: Drittanbieter-Cookies):<\/strong> Drittanbieter-Cookies werden haupts\u00e4chlich von Werbetreibenden (sog. Dritten) verwendet, um Benutzerinformationen zu verarbeiten.<\/li>\n<li><strong>Notwendige (auch: essentielle oder unbedingt erforderliche) Cookies:<\/strong> Cookies k\u00f6nnen zum einen f\u00fcr den Betrieb einer Webseite unbedingt erforderlich sein (z.B. um Logins oder andere Nutzereingaben zu speichern oder aus Gr\u00fcnden der Sicherheit).<\/li>\n<li><strong>Statistik-, Marketing- und Personalisierungs-Cookies:<\/strong> Ferner werden Cookies im Regelfall auch im Rahmen der Reichweitenmessung eingesetzt sowie dann, wenn die Interessen eines Nutzers oder sein Verhalten (z.B. Betrachten bestimmter Inhalte, Nutzen von Funktionen etc.) auf einzelnen Webseiten in einem Nutzerprofil gespeichert werden. Solche Profile dienen dazu, den Nutzern z.B. Inhalte anzuzeigen, die ihren potentiellen Interessen entsprechen. Dieses Verfahren wird auch als &#8220;Tracking&#8221;, d.h., Nachverfolgung der potentiellen Interessen der Nutzer bezeichnet. Soweit wir Cookies oder &#8220;Tracking&#8221;-Technologien einsetzen, informieren wir Sie gesondert in unserer Datenschutzerkl\u00e4rung oder im Rahmen der Einholung einer Einwilligung.<\/li>\n<\/ul>\n<p><strong>Hinweise zu Rechtsgrundlagen: <\/strong>Auf welcher Rechtsgrundlage wir Ihre personenbezogenen Daten mit Hilfe von Cookies verarbeiten, h\u00e4ngt davon ab, ob wir Sie um eine Einwilligung bitten. Falls dies zutrifft und Sie in die Nutzung von Cookies einwilligen, ist die Rechtsgrundlage der Verarbeitung Ihrer Daten die erkl\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verarbeiteten Daten auf Grundlage unserer berechtigten Interessen (z.B. an einem betriebswirtschaftlichen Betrieb unseres Onlineangebotes und dessen Verbesserung) verarbeitet oder, wenn der Einsatz von Cookies erforderlich ist, um unsere vertraglichen Verpflichtungen zu erf\u00fcllen.<\/p>\n<p><strong>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-Out): <\/strong>Abh\u00e4ngig davon, ob die Verarbeitung auf Grundlage einer Einwilligung oder gesetzlichen Erlaubnis erfolgt, haben Sie jederzeit die M\u00f6glichkeit, eine erteilte Einwilligung zu widerrufen oder der Verarbeitung Ihrer Daten durch Cookie-Technologien zu widersprechen (zusammenfassend als &#8220;Opt-Out&#8221; bezeichnet). Sie k\u00f6nnen Ihren Widerspruch zun\u00e4chst mittels der Einstellungen Ihres Browsers erkl\u00e4ren, z.B., indem Sie die Nutzung von Cookies deaktivieren (wobei hierdurch auch die Funktionsf\u00e4higkeit unseres Onlineangebotes eingeschr\u00e4nkt werden kann). Ein Widerspruch gegen den Einsatz von Cookies zu Zwecken des Onlinemarketings kann auch mittels einer Vielzahl von Diensten, vor allem im Fall des Trackings, \u00fcber die Webseiten <a href=\"http:\/\/optout.aboutads.info\/\" target=\"_blank\" rel=\"noopener\">http:\/\/optout.aboutads.info<\/a> und <a href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.youronlinechoices.com\/<\/a> erkl\u00e4rt werden. Daneben k\u00f6nnen Sie weitere Widerspruchshinweise im Rahmen der Angaben zu den eingesetzten Dienstleistern und Cookies erhalten.<\/p>\n<p><strong>Verarbeitung von Cookie-Daten auf Grundlage einer Einwilligung:<\/strong> Bevor wir Daten im Rahmen der Nutzung von Cookies verarbeiten oder verarbeiten lassen, bitten wir die Nutzer um eine jederzeit widerrufbare Einwilligung. Bevor die Einwilligung nicht ausgesprochen wurde, werden allenfalls Cookies eingesetzt, die f\u00fcr den Betrieb unseres Onlineangebotes erforderlich sind. Deren Einsatz erfolgt auf der Grundlage des Interesses der Nutzer an der erwarteten Funktionsf\u00e4higkeit unseres Onlineangebotes.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten)<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Vimeo&#8221;][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 id=\"m789\">Vimeo<\/h3>\n<p>Unsere Website nutzt Plugins des Videoportals Vimeo. Anbieter ist die Vimeo Inc., 555 West 18th Street, New York, New York 10011, USA.<\/p>\n<p>Wenn Sie eine unserer mit einem Vimeo-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von Vimeo hergestellt. Dabei wird dem Vimeo-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Zudem erlangt Vimeo Ihre IP-Adresse. Dies gilt auch dann, wenn Sie nicht bei Vimeo eingeloggt sind oder keinen Account bei Vimeo besitzen. Die von Vimeo erfassten Informationen werden an den Vimeo-Server in den USA \u00fcbermittelt. F\u00fcr die USA ist ein Angemessenheitsbeschluss der EU-Kommission vorhanden, das &#8220;Data Privacy Framework&#8221; (DPF). Vimeo hat sich nach dem DPF zertifiziert und damit verpflichtet, europ\u00e4ische Datenschutzgrunds\u00e4tze einzuhalten.<\/p>\n<p>Wenn Sie in Ihrem Vimeo-Account eingeloggt sind, erm\u00f6glichen Sie Vimeo, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem Vimeo-Account ausloggen.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Vimeo unter:<br \/>\n<a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/vimeo.com\/privacy<\/a>.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Calendly&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m789\">Calendly<\/h3>\n<p>Zur einfachen, schnellen und unkomplizierten Terminvereinbarung setzen wir das Tool calendly ein. Die Nutzung von calendly erfolgt zur Verbesserung unserer Dienstleistung f\u00fcr bestehende und neue Mitglieder. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p>Bei der Verwendung des Tools werden von Ihnen pers\u00f6nliche Daten wie Name, E-Mail-Adresse und Telefonnummer abgefragt. Sie haben au\u00dferdem die M\u00f6glichkeit, Ihr Anliegen darzustellen und uns weitere Informationen zur Verf\u00fcgung zu stellen. Wenn Sie das Tool nutzen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Informationen gespeichert und selbstverst\u00e4ndlich im Internet \u00fcbertragen. Die Verarbeitung der eingegebenen Daten erfolgt ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO).<\/p>\n<p>F\u00fcr den Umgang mit den durch Verwendung von calendly erfassten Daten gilt diese Datenschutzerkl\u00e4rung sowie die Datenschutzerkl\u00e4rung des Anbieters. Die Datenschutzerkl\u00e4rung von calendly finden Sie unter:<\/p>\n<p><a href=\"https:\/\/calendly.com\/pages\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/calendly.com\/pages\/privacy<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Wahrnehmung von Aufgaben nach Satzung oder Gesch\u00e4ftsordnung&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m354\">Wahrnehmung von Aufgaben nach Satzung oder Gesch\u00e4ftsordnung<\/h3>\n<p>Wir verarbeiten die Daten unserer Mitglieder, der Organe und Besch\u00e4ftigten unserer Mitglieder, Unterst\u00fctzer, Interessenten, Gesch\u00e4ftspartner oder sonstiger Personen (Zusammenfassend &#8220;Betroffene&#8221;), wenn wir mit ihnen in einem Mitgliedschafts- oder sonstigem gesch\u00e4ftlichen Verh\u00e4ltnis stehen und unsere Aufgaben wahrnehmen sowie Empf\u00e4nger von Leistungen und Zuwendungen sind. Im \u00dcbrigen verarbeiten wir die Daten Betroffener auf Grundlage unserer berechtigten Interessen, z.B. wenn es sich um administrative Aufgaben oder \u00d6ffentlichkeitsarbeit handelt.<\/p>\n<p>Die hierbei verarbeiteten Daten, die Art, der Umfang und der Zweck und die Erforderlichkeit ihrer Verarbeitung, bestimmen sich nach dem zugrundeliegenden Mitgliedschafts- oder Vertragsverh\u00e4ltnis, aus dem sich auch die Erforderlichkeit etwaiger Datenangaben ergeben (im \u00dcbrigen weisen wir auf erforderliche Daten hin).<\/p>\n<p>Wir l\u00f6schen Daten, die zur Erbringung unserer satzungs- und gesch\u00e4ftsm\u00e4\u00dfigen Zwecke nicht mehr erforderlich sind. Dies bestimmt sich entsprechend der jeweiligen Aufgaben und vertraglichen Beziehungen. Wir bewahren die Daten so lange auf, wie sie zur Gesch\u00e4ftsabwicklung, als auch im Hinblick auf etwaige Gew\u00e4hrleistungs- oder Haftungspflichten auf Grundlage unserer berechtigten Interesse an deren Regelung relevant sein k\u00f6nnen. Die Erforderlichkeit der Aufbewahrung der Daten wird regelm\u00e4\u00dfig \u00fcberpr\u00fcft; im \u00dcbrigen gelten die gesetzlichen Aufbewahrungspflichten.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Zahlungsdaten (z.B. Bankverbindungen, Rechnungen, Zahlungshistorie), Kontaktdaten (z.B. E-Mail, Telefonnummern), Mitgliedsdaten (z.B. Beitrittsdatum, Beitrag)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten), Besch\u00e4ftigte von Mitgliedern, Gesch\u00e4fts- und Vertragspartner, Interessenten<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Vertragliche Leistungen und Service, Kontaktanfragen und Kommunikation, Verwaltung und Beantwortung von Anfragen<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;(Online-)Veranstaltungen und Seminare&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m355\">(Online-)Veranstaltungen und Seminare<\/h3>\n<p>Bei der Durchf\u00fchrung von (Online-)Veranstaltungen und Seminaren k\u00f6nnen Daten zur Organisation, Durchf\u00fchrung und Dokumentation der Veranstaltungen und Seminare erhoben werden.<\/p>\n<p>Innerhalb unseres Verbandes erhalten nur die Personen und Stellen Ihre personenbezogenen Daten, die diese zur Erf\u00fcllung des Zweckes oder zur Wahrung der berechtigten Interessen ben\u00f6tigen. Ggf. werden Fotos an externe Dritte zum Zwecke der \u00d6ffentlichkeitsarbeit weitergegeben.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), ggf. Fotos, bei Online-Veranstaltungen: zus\u00e4tzlich Ton- und Videodaten, Logdateien (z.B. IP-Adresse)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Referenten, Teilnehmer, Interessenten, Gesch\u00e4fts- und Vertragspartner<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Organisation und Durchf\u00fchrung von (Online-)Veranstaltungen und Seminaren<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Rechtsberatung und Prozessvertretung&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m356\">Rechtsberatung und Prozessvertretung<\/h3>\n<p>F\u00fcr unsere Mitglieder erbringen wir auf Grundlage von \u00a7 5 Abs. 1 RDG, \u00a7 11 Abs. 2 ArbGG sowie Art. 9 Abs. 3 GG Rechtsdienstleistungen, insbesondere in Form von arbeits- und sozialrechtlicher Beratung und Prozessvertretung.<\/p>\n<p>Innerhalb unseres Verbandes erhalten nur die Personen und Stellen Ihre personenbezogenen Daten, die diese zur Erf\u00fcllung des Zweckes oder zur Wahrung der berechtigten Interessen ben\u00f6tigen. Extern werden die Daten nur zur Zweckerf\u00fcllung an Dritte weitergegeben, dies k\u00f6nnen insbesondere Verfahrensbeteiligte und deren Vertreter, sowie Gerichte und andere \u00f6ffentliche Beh\u00f6rden zum Zwecke der Korrespondenz sowie zur Geltendmachung und Verteidigung der Rechte unserer Mitglieder sein.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Informationen, die f\u00fcr die Geltendmachung und Verteidigung von Rechten im Rahmen der Rechtsberatung notwendig sind (z.B. Sachverhaltsdaten, Sozialdaten)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Ansprechpartner, Verfahrensbeteiligte<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Rechtsberatung und Prozessvertretung insbesondere bei arbeits- und sozialrechtlichen Fragen<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<li><strong>Verarbeitung besonderer Kategorien von Daten:<\/strong> Soweit im Rahmen der Rechtsberatung und Prozessvertretung besondere Kategorien von personenbezogenen Daten im Sinne des Art. 9 Abs. 1 DSGVO (z.B. Gesundheitsdaten, Schwerbehinderteneigenschaft oder ethnische Herkunft) verarbeitet werden, ist die Verarbeitung zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich. Dies insbesondere, damit unsere Mitglieder ihnen aus dem Arbeitsrecht und dem Recht der sozialen Sicherheit und des Sozialschutzes erwachsenden Rechte aus\u00fcben und ihren diesbez\u00fcglichen Pflichten nachkommen k\u00f6nnen. Die Verarbeitung erfolgt nach Art. 9 Abs. 2 lit. f. DSGVO.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Datenschutzmanagement&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m357\">Datenschutzmanagement<\/h3>\n<p>Soweit eine Datenschutzanfrage an uns gestellt wird sowie zur Gew\u00e4hrleistung des Datenschutzmanagements k\u00f6nnen personenbezogene Daten erhoben und verarbeitet werden.<\/p>\n<p>Innerhalb unseres Verbandes erhalten nur die Personen und Stellen Ihre personenbezogenen Daten, die diese zur Erf\u00fcllung des Zweckes oder zur Wahrung der berechtigten Interessen ben\u00f6tigen. Extern werden die Daten erforderlichenfalls an den Datenschutzbeauftragten sowie die diesbez\u00fcglichen Aufsichtsbeh\u00f6rden weitergegeben.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), die durch die Anfragenden mitgeteilten Daten<\/li>\n<li><strong>Betroffene Personen:<\/strong> Betroffene Personen (&#8220;Anfragender&#8221;), Datenschutzbeauftragter<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bearbeitung von Datenschutzanfragen, Nachhaltung und Gew\u00e4hrleistung des Datenschutzes<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Erf\u00fcllung rechtlicher Verpflichtungen (Art. 6 Abs. 1 S. 1 lit. c. DSGVO), Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Registrierung und Anmeldung&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m367\">Registrierung und Anmeldung<\/h3>\n<p>F\u00fcr Nutzer der Homepage kann ein Nutzerkonto angelegt werden. Im Rahmen der Registrierung werden den Nutzern die erforderlichen Pflichtangaben mitgeteilt und zu Zwecken der Bereitstellung des Nutzerkontos auf Grundlage vertraglicher Pflichterf\u00fcllung verarbeitet. Zu den verarbeiteten Daten geh\u00f6ren insbesondere die Login-Informationen (Name, Passwort sowie eine E-Mail-Adresse). Die im Rahmen der Registrierung eingegebenen Daten werden f\u00fcr die Zwecke der Nutzung des Nutzerkontos und dessen Zwecks verwendet.<\/p>\n<p>Die Nutzer k\u00f6nnen \u00fcber Vorg\u00e4nge, die f\u00fcr deren Nutzerkonto relevant sind, wie z.B. technische \u00c4nderungen, per E-Mail informiert werden. Wenn Nutzer ihr Nutzerkonto gek\u00fcndigt haben, werden deren Daten im Hinblick auf das Nutzerkonto, vorbehaltlich einer gesetzlichen Aufbewahrungspflicht, gel\u00f6scht. Es obliegt den Nutzern, ihre Daten bei erfolgter K\u00fcndigung vor dem Vertragsende zu sichern. Wir sind berechtigt, s\u00e4mtliche w\u00e4hrend der Vertragsdauer gespeicherte Daten des Nutzers unwiederbringlich zu l\u00f6schen.<\/p>\n<p>Im Rahmen der Inanspruchnahme unserer Registrierungs- und Anmeldefunktionen sowie der Nutzung des Nutzerkontos speichern wir die IP-Adresse und den Zeitpunkt der jeweiligen Nutzerhandlung. Die Speicherung erfolgt auf Grundlage unserer berechtigten Interessen als auch jener der Nutzer an einem Schutz vor Missbrauch und sonstiger unbefugter Nutzung. Eine Weitergabe dieser Daten an Dritte erfolgt grunds\u00e4tzlich nicht, es sei denn, sie ist zur Verfolgung unserer Anspr\u00fcche erforderlich oder es besteht hierzu besteht eine gesetzliche Verpflichtung.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten)<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Vertragliche Leistungen und Service, Sicherheitsma\u00dfnahmen, Verwaltung und Beantwortung von Anfragen<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Kontaktaufnahme&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m182\">Kontaktaufnahme<\/h3>\n<p>Bei der Kontaktaufnahme mit uns (z.B. per Kontaktformular, E-Mail oder Telefon) werden die Angaben der anfragenden Personen verarbeitet, soweit dies zur Beantwortung der Kontaktanfragen und etwaiger angefragter Ma\u00dfnahmen erforderlich ist.<\/p>\n<p>Die Beantwortung der Kontaktanfragen im Rahmen von vertraglichen oder vorvertraglichen Beziehungen erfolgt zur Erf\u00fcllung unserer vertraglichen Pflichten oder zur Beantwortung von (vor)vertraglichen Anfragen und im \u00dcbrigen auf Grundlage der berechtigten Interessen an der Beantwortung der Anfragen.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Kommunikationspartner<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Kontaktanfragen und Kommunikation<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Bereitstellung des Onlineangebotes und Webhosting&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m225\">Bereitstellung des Onlineangebotes und Webhosting<\/h3>\n<p>Um unser Onlineangebot sicher und effizient bereitstellen zu k\u00f6nnen, nehmen wir die Leistungen von einem oder mehreren Webhosting-Anbietern in Anspruch, von deren Servern (bzw. von ihnen verwalteten Servern) das Onlineangebot abgerufen werden kann. Zu diesen Zwecken k\u00f6nnen wir Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\u00e4t, Speicherplatz und Datenbankdienste sowie Sicherheitsleistungen und technische Wartungsleistungen in Anspruch nehmen.<\/p>\n<p>Zu den im Rahmen der Bereitstellung des Hostingangebotes verarbeiteten Daten k\u00f6nnen alle die Nutzer unseres Onlineangebotes betreffenden Angaben geh\u00f6ren, die im Rahmen der Nutzung und der Kommunikation anfallen. Hierzu geh\u00f6ren regelm\u00e4\u00dfig die IP-Adresse, die notwendig ist, um die Inhalte von Onlineangeboten an Browser ausliefern zu k\u00f6nnen, und alle innerhalb unseres Onlineangebotes oder von Webseiten get\u00e4tigten Eingaben.<\/p>\n<p><strong>E-Mail-Versand und -Hosting:<\/strong> Die von uns in Anspruch genommenen Webhosting-Leistungen umfassen ebenfalls den Versand, den Empfang sowie die Speicherung von E-Mails. Zu diesen Zwecken werden die Adressen der Empf\u00e4nger sowie Absender als auch weitere Informationen betreffend den E-Mailversand (z.B. die beteiligten Provider) sowie die Inhalte der jeweiligen E-Mails verarbeitet. Die vorgenannten Daten k\u00f6nnen ferner zu Zwecken der Erkennung von SPAM verarbeitet werden. Wir bitten darum, zu beachten, dass E-Mails im Internet grunds\u00e4tzlich nicht verschl\u00fcsselt versendet werden. Im Regelfall werden E-Mails zwar auf dem Transportweg verschl\u00fcsselt, aber (sofern kein sogenanntes Ende-zu-Ende-Verschl\u00fcsselungsverfahren eingesetzt wird) nicht auf den Servern, von denen sie abgesendet und empfangen werden. Wir k\u00f6nnen daher f\u00fcr den \u00dcbertragungsweg der E-Mails zwischen dem Absender und dem Empfang auf unserem Server keine Verantwortung \u00fcbernehmen.<\/p>\n<p><strong>Erhebung von Zugriffsdaten und Logfiles:<\/strong> Wir selbst (bzw. unser Webhostinganbieter) erheben Daten zu jedem Zugriff auf den Server (sogenannte Serverlogfiles). Zu den Serverlogfiles k\u00f6nnen die Adresse und Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmengen, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende Provider geh\u00f6ren.<\/p>\n<p>Die Serverlogfiles k\u00f6nnen zum einen zu Zwecken der Sicherheit eingesetzt werden, z.B., um eine \u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\u00e4uchlichen Angriffen, sogenannten DDoS-Attacken) und zum anderen, um die Auslastung der Server und ihre Stabilit\u00e4t sicherzustellen.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten)<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Bewerbungsverfahren und Personaladministration&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m210\">Bewerbungsverfahren und Personaladministration<\/h3>\n<p>Das Bewerbungsverfahren setzt voraus, dass Bewerber uns die f\u00fcr deren Beurteilung und Auswahl erforderlichen Daten mitteilen. Welche Informationen erforderlich sind, ergibt sich aus der Stellenbeschreibung oder im Fall von Onlineformularen aus den dortigen Angaben.<\/p>\n<p>Grunds\u00e4tzlich geh\u00f6ren zu den erforderlichen Angaben, die Informationen zur Person, wie der Name, die Adresse, eine Kontaktm\u00f6glichkeit sowie die Nachweise \u00fcber die f\u00fcr eine Stelle notwendigen Qualifikationen. Auf Anfragen teilen wir zus\u00e4tzlich gerne mit, welche Angaben ben\u00f6tigt werden.<\/p>\n<p>Sofern zur Verf\u00fcgung gestellt, k\u00f6nnen uns Bewerber ihre Bewerbungen mittels eines Onlineformulars \u00fcbermitteln. Die Daten werden entsprechend dem Stand der Technik verschl\u00fcsselt an uns \u00fcbertragen. Ebenfalls k\u00f6nnen Bewerber uns ihre Bewerbungen via E-Mail \u00fcbermitteln. Hierbei bitten wir jedoch zu beachten, dass E-Mails im Internet grunds\u00e4tzlich nicht verschl\u00fcsselt versendet werden. Im Regelfall werden E-Mails zwar auf dem Transportweg verschl\u00fcsselt, aber nicht auf den Servern von denen sie abgesendet und empfangen werden. Wir k\u00f6nnen daher f\u00fcr den \u00dcbertragungsweg der Bewerbung zwischen dem Absender und dem Empfang auf unserem Server keine Verantwortung \u00fcbernehmen.<\/p>\n<p>F\u00fcr Zwecke der Bewerbersuche, Einreichung von Bewerbungen und Auswahl von Bewerbern k\u00f6nnen wir unter Beachtung der gesetzlichen Vorgaben, Bewerbermanagement-, bzw. Recruitment-Software und Plattformen und Leistungen von Drittanbietern in Anspruch nehmen.<\/p>\n<p>Bewerber k\u00f6nnen uns gerne zur Art der Einreichung der Bewerbung kontaktieren oder uns die Bewerbung auf dem Postweg zuzusenden.<\/p>\n<p>Nach erfolgreicher Bewerbung werden die Daten des eingestellten Bewerbers zur Personaladministration verwendet.<\/p>\n<p><strong>L\u00f6schung von Daten:<\/strong> Die von den Bewerbern zur Verf\u00fcgung gestellten Daten k\u00f6nnen im Fall einer erfolgreichen Bewerbung f\u00fcr die Zwecke des Besch\u00e4ftigungsverh\u00e4ltnisses (Personaladministration) von uns weiterverarbeitet werden. Andernfalls, sofern die Bewerbung auf ein Stellenangebot nicht erfolgreich ist, werden die Daten der Bewerber gel\u00f6scht. Die Daten der Bewerber werden ebenfalls gel\u00f6scht, wenn eine Bewerbung zur\u00fcckgezogen wird, wozu die Bewerber jederzeit berechtigt sind. Die L\u00f6schung erfolgt, vorbehaltlich eines berechtigten Widerrufs der Bewerber, sp\u00e4testens nach dem Ablauf eines Zeitraums von sechs Monaten, damit wir etwaige Anschlussfragen zu der Bewerbung beantworten und unseren Nachweispflichten aus den Vorschriften zur Gleichbehandlung von Bewerbern nachkommen k\u00f6nnen. Rechnungen \u00fcber etwaige Reisekostenerstattung werden entsprechend den steuerrechtlichen Vorgaben archiviert.<\/p>\n<p><strong>Aufnahme in einen Bewerberpool:<\/strong> Die Aufnahme in einen Bewerber-Pool, sofern angeboten, erfolgt auf Grundlage einer Einwilligung. Die Bewerber werden dar\u00fcber belehrt, dass ihre Zustimmung zur Aufnahme in den Talentpool freiwillig ist, keinen Einfluss auf das laufende Bewerbungsverfahren hat und sie ihre Einwilligung jederzeit f\u00fcr die Zukunft widerrufen k\u00f6nnen.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bewerberdaten (z.B. Angaben zur Person, Post- und Kontaktadressen, die zur Bewerbung geh\u00f6renden Unterlagen und die darin enthaltenen Informationen, wie z.B. Anschreiben, Lebenslauf, Zeugnisse sowie weitere im Hinblick auf eine konkrete Stelle oder freiwillig von Bewerbern mitgeteilte Informationen zu deren Person oder Qualifikation), Personaldaten (z.B. Sozialversicherungsnummer, Steuernummer, Kontoverbindung, Sozialdaten)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Bewerber und Besch\u00e4ftigte<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bewerbungsverfahren und Personaladministration (Begr\u00fcndung und etwaige sp\u00e4tere Durchf\u00fchrung sowie m\u00f6gliche sp\u00e4tere Beendigung des Besch\u00e4ftigungsverh\u00e4ltnisses.)<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Art. 9 Abs. 1 S. 1 lit. b DSGVO (Bewerbungsverfahren als vorvertragliches bzw. vertragliches Verh\u00e4ltnis)<\/li>\n<li><strong>Verarbeitung besonderer Kategorien von Daten:<\/strong> Soweit im Rahmen des Bewerbungsverfahrens und der Personaladministration besondere Kategorien von personenbezogenen Daten im Sinne des Art. 9 Abs. 1 DSGVO (z.B. Gesundheitsdaten, wie z.B. Schwerbehinderteneigenschaft oder ethnische Herkunft) bei Bewerbern erhoben werden, damit der Verantwortliche oder die betroffene Person die ihm bzw. ihr aus dem Arbeitsrecht und dem Recht der sozialen Sicherheit und des Sozialschutzes erwachsenden Rechte aus\u00fcben und seinen bzw. ihren diesbez\u00fcglichen Pflichten nachkommen kann, erfolgt deren Verarbeitung nach Art. 9 Abs. 2 lit. b. DSGVO, im Fall des Schutzes lebenswichtiger Interessen der Bewerber oder anderer Personen gem. Art. 9 Abs. 2 lit. c. DSGVO oder f\u00fcr Zwecke der Gesundheitsvorsorge oder der Arbeitsmedizin, f\u00fcr die Beurteilung der Arbeitsf\u00e4higkeit des Besch\u00e4ftigten, f\u00fcr die medizinische Diagnostik, f\u00fcr die Versorgung oder Behandlung im Gesundheits- oder Sozialbereich oder f\u00fcr die Verwaltung von Systemen und Diensten im Gesundheits- oder Sozialbereich gem. Art. 9 Abs. 2 lit. h. DSGVO. Im Fall einer auf freiwilliger Einwilligung beruhenden Mitteilung der besonderen Kategorien von Daten erfolgt deren Verarbeitung auf Grundlage von Art. 9 Abs. 2 lit. a. DSGVO.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Newsletter und Breitenkommunikation&#8221;][vc_column][vc_column_text]<\/p>\n<h3>Newsletter und Breitenkommunikation<\/h3>\n<p>Wir versenden Newsletter, E-Mails und weitere elektronische Benachrichtigungen (nachfolgend &#8220;Newsletter\u201c) nur mit der Einwilligung der Empf\u00e4nger oder einer gesetzlichen Erlaubnis. Sofern im Rahmen einer Anmeldung zum Newsletter dessen Inhalte konkret umschrieben werden, sind sie f\u00fcr die Einwilligung der Nutzer ma\u00dfgeblich. Im \u00dcbrigen enthalten unsere Newsletter Informationen zu unseren Leistungen und uns.<\/p>\n<p>Um sich zu unseren Newslettern anzumelden, reicht es grunds\u00e4tzlich aus, wenn Sie Ihre E-Mail-Adresse angeben. Wir k\u00f6nnen Sie jedoch bitten, einen Namen, zwecks pers\u00f6nlicher Ansprache im Newsletter, oder weitere Angaben, sofern diese f\u00fcr die Zwecke des Newsletters erforderlich sind, zu t\u00e4tigen.<\/p>\n<p><strong>Double-Opt-In-Verfahren:<\/strong> Die Anmeldung zu unserem Newsletter erfolgt grunds\u00e4tzlich in einem sogenannte Double-Opt-In-Verfahren. D.h., Sie erhalten nach der Anmeldung eine E-Mail, in der Sie um die Best\u00e4tigung Ihrer Anmeldung gebeten werden. Diese Best\u00e4tigung ist notwendig, damit sich niemand mit fremden E-Mail-Adressen anmelden kann. Die Anmeldungen zum Newsletter werden protokolliert, um den Anmeldeprozess entsprechend den rechtlichen Anforderungen nachweisen zu k\u00f6nnen. Hierzu geh\u00f6rt die Speicherung des Anmelde- und des Best\u00e4tigungszeitpunkts als auch der IP-Adresse. Ebenso werden die \u00c4nderungen Ihrer bei dem Versanddienstleister gespeicherten Daten protokolliert.<\/p>\n<p><strong>L\u00f6schung und Einschr\u00e4nkung der Verarbeitung: <\/strong>Wir k\u00f6nnen die ausgetragenen E-Mail-Adressen bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie l\u00f6schen, um eine ehemals gegebene Einwilligung nachweisen zu k\u00f6nnen. Die Verarbeitung dieser Daten wird auf den Zweck einer m\u00f6glichen Abwehr von Anspr\u00fcchen beschr\u00e4nkt. Ein individueller L\u00f6schungsantrag ist jederzeit m\u00f6glich, sofern zugleich das ehemalige Bestehen einer Einwilligung best\u00e4tigt wird. Im Fall von Pflichten zur dauerhaften Beachtung von Widerspr\u00fcchen behalten wir uns die Speicherung der E-Mail-Adresse alleine zu diesem Zweck in einer Sperrliste (sogenannte &#8220;Blacklist&#8221;) vor.<\/p>\n<p>Die Protokollierung des Anmeldeverfahrens erfolgt auf Grundlage unserer berechtigten Interessen zu Zwecken des Nachweises seines ordnungsgem\u00e4\u00dfen Ablaufs. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, erfolgt dies auf Grundlage unserer berechtigten Interessen an einem effizienten und sicheren Versandsystem.<\/p>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Der Versand der Newsletter erfolgt auf Grundlage einer Einwilligung der Empf\u00e4nger oder, falls eine Einwilligung nicht erforderlich ist, auf Grundlage unserer berechtigten Interessen am Direktmarketing, sofern und soweit diese gesetzlich, z.B. im Fall von Bestandskundenwerbung, erlaubt ist. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, geschieht dies auf der Grundlage unserer berechtigten Interessen. Das Registrierungsverfahren wird auf der Grundlage unserer berechtigten Interessen aufgezeichnet, um nachzuweisen, dass es in \u00dcbereinstimmung mit dem Gesetz durchgef\u00fchrt wurde.<\/p>\n<p><strong>Inhalte:<\/strong> Informationen zu uns, unseren Leistungen, Veranstaltungen, und Angeboten. Dar\u00fcber hinaus versenden wir Rundschreiben zu aktuellen verbandlichen Themen.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Kommunikationspartner<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Information \u00fcber die Verb\u00e4ndegemeinschaft, Marketing (z.B. per E-Mail oder postalisch)<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<li><strong>Widerspruchsm\u00f6glichkeit (Opt-Out):<\/strong> Sie k\u00f6nnen den Empfang unseres Newsletters jederzeit k\u00fcndigen, d.h. Ihre Einwilligungen widerrufen bzw. dem weiteren Empfang widersprechen. Einen Link zur K\u00fcndigung des Newsletters finden Sie entweder am Ende eines jeden Newsletters oder k\u00f6nnen sonst eine der oben angegebenen Kontaktm\u00f6glichkeiten, vorzugsw\u00fcrdig E-Mail, hierzu nutzen.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;Akquise&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m638\">Akquise<\/h3>\n<p>Wir verarbeiten personenbezogene Daten zu Zwecken Akquise, die \u00fcber diverse Kan\u00e4le, wie z.B. E-Mail, Telefon, Post oder Fax, entsprechend den gesetzlichen Vorgaben erfolgen kann.<\/p>\n<p>Die Empf\u00e4nger haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen oder der werblichen Kommunikation jederzeit zu widersprechen.<\/p>\n<p>Nach Widerruf bzw. Widerspruch k\u00f6nnen wir die zum Nachweis der Einwilligung erforderlichen Daten bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie l\u00f6schen. Die Verarbeitung dieser Daten wird auf den Zweck einer m\u00f6glichen Abwehr von Anspr\u00fcchen beschr\u00e4nkt. Ein individueller L\u00f6schungsantrag ist jederzeit m\u00f6glich, sofern zugleich das ehemalige Bestehen einer Einwilligung best\u00e4tigt wird.<\/p>\n<ul class=\"m-elements\">\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern)<\/li>\n<li><strong>Betroffene Personen:<\/strong> Kommunikationspartner und Interessenten<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Mitgliedswerbung und Direktmarketing (z.B. per E-Mail oder postalisch)<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;UmfrageOnline&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m444\">UmfrageOnline<\/h3>\n<p>Wir f\u00fchren Umfragen und Befragungen (nachfolgend \u201eBefragungen\u201c) durch. Dies dient dazu, unsere Angebote zu verbessern und auf die Bed\u00fcrfnisse unserer Mitglieder besser eingehen zu k\u00f6nnen. Die Teilnahme an einer Umfrage erfolgt freiwillig.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten: <\/strong>Meta- und Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adresse), Nutzungsdaten (z.B. Interessen, Zugriffszeiten), Stammdaten (z.B. Name, Adresse), Kontaktdaten (z.B. E-Mail-Adresse)<\/li>\n<li><strong>Betroffene Personen: <\/strong>Teilnehmer an Befragungen<\/li>\n<li><strong>Zwecke der Verarbeitung: <\/strong>Anmeldung zu Veranstaltungen, Einholen von Stimmungsbildern und Feedback, Verbesserung \/ Optimierung des Angebots<\/li>\n<li><strong>Rechtsgrundlagen: <\/strong>Einwilligung (Art. 6 Abs. 1 Buchst. a) DSGVO) bzw. berechtigtes Interesse (Art. 6 Abs. 1 lit. f) DSGVO)<\/li>\n<\/ul>\n<p>UmfrageOnline verarbeitet die von Ihnen angegebenen Daten in unserem Auftrag. Wir haben mit enuvo einen Auftragsverarbeitungsvertrag nach Art. 28 DSGVO geschlossen. Die Datenverarbeitung erfolgt bei Amazon Web Services EMEA SARL in Rechenzentren innerhalb der EU (Region Irland und\/oder Frankfurt). Die Datenschutzerkl\u00e4rung von UmfrageOnline finden Sie unter <a href=\"https:\/\/www.umfrageonline.com\/datenschutz\" target=\"_blank\" rel=\"noopener\">https:\/\/www.umfrageonline.com\/datenschutz<\/a>.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;L\u00f6schung von Daten&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m12\">L\u00f6schung von Daten<\/h3>\n<p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der gesetzlichen Vorgaben gel\u00f6scht, sobald deren zur Verarbeitung erlaubten Einwilligungen widerrufen werden oder sonstige Erlaubnisse entfallen (z.B., wenn der Zweck der Verarbeitung dieser Daten entfallen ist oder sie f\u00fcr den Zweck nicht erforderlich sind).<\/p>\n<p>Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung auf diese Zwecke beschr\u00e4nkt. D.h., die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen oder deren Speicherung zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person erforderlich ist.<\/p>\n<p>Weitere Hinweise zu der L\u00f6schung von personenbezogenen Daten k\u00f6nnen ferner im Rahmen der einzelnen Datenschutzhinweise dieser Datenschutzerkl\u00e4rung erfolgen.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=&#8221;\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m15\">\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/h3>\n<p>Wir bitten Sie, sich regelm\u00e4\u00dfig \u00fcber den Inhalt unserer Datenschutzerkl\u00e4rung zu informieren. Wir passen die Datenschutzerkl\u00e4rung an, sobald die \u00c4nderungen der von uns durchgef\u00fchrten Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \u00c4nderungen eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle Benachrichtigung erforderlich wird.<\/p>\n<p>Sofern wir in dieser Datenschutzerkl\u00e4rung Adressen und Kontaktinformationen von Unternehmen und Organisationen angeben, bitten wir zu beachten, dass die Adressen sich \u00fcber die Zeit \u00e4ndern k\u00f6nnen und bitten die Angaben vor Kontaktaufnahme zu pr\u00fcfen.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1688722874595{margin-bottom: 50px !important;}&#8221; el_id=&#8221;Rechte der betroffenen Personen&#8221;][vc_column][vc_column_text]<\/p>\n<h3 id=\"m10\">Rechte der betroffenen Personen<\/h3>\n<p>Ihnen stehen als Betroffene nach der DSGVO verschiedene Rechte zu, die sich insbesondere aus Art. 15 bis 18 und 21 DSGVO ergeben:<\/p>\n<ul>\n<li><strong>Widerspruchsrecht: Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<\/strong><\/li>\n<li><strong>Widerrufsrecht bei Einwilligungen:<\/strong> Sie haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen.<\/li>\n<li><strong>Auskunftsrecht:<\/strong> Sie haben das Recht, eine Best\u00e4tigung dar\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend den gesetzlichen Vorgaben.<\/li>\n<li><strong>Recht auf Berichtigung:<\/strong> Sie haben entsprechend den gesetzlichen Vorgaben das Recht, die Vervollst\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\/li>\n<li><strong>Recht auf L\u00f6schung und Einschr\u00e4nkung der Verarbeitung:<\/strong> Sie haben nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, zu verlangen, dass Sie betreffende Daten unverz\u00fcglich gel\u00f6scht werden, bzw. alternativ nach Ma\u00dfgabe der gesetzlichen Vorgaben eine Einschr\u00e4nkung der Verarbeitung der Daten zu verlangen.<\/li>\n<li><strong>Recht auf Daten\u00fcbertragbarkeit:<\/strong> Sie haben das Recht, Sie betreffende Daten, die Sie uns bereitgestellt haben, nach Ma\u00dfgabe der gesetzlichen Vorgaben in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten oder deren \u00dcbermittlung an einen anderen Verantwortlichen zu fordern.<\/li>\n<li><strong>Aus\u00fcbung der Betroffenenrechte:<\/strong> Gerne k\u00f6nnen Sie sich zur Aus\u00fcbung Ihrer Betroffenenrechte an den Verantwortlichen oder unseren Datenschutzbeauftragten wenden. Die Kontaktdaten des Verantwortlichen finden Sie <strong><a href=\"#Verantwortlicher\">hier<\/a><\/strong>. Die Kontaktdaten des Datenschutzbeauftragten finden Sie <strong><a href=\"#Kontakt Datenschutzbeauftragter\">hier<\/a><\/strong>.<\/li>\n<li><strong>Beschwerde bei Aufsichtsbeh\u00f6rde:<\/strong> Sie haben ferner nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat Ihres gew\u00f6hnlichen Aufenthaltsorts, Ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes, wenn Sie der Ansicht sind, dass die Verarbeitung der Sie betreffenden personenbezogenen Daten gegen die DSGVO verst\u00f6\u00dft.<\/li>\n<\/ul>\n<p><strong>F\u00fcr uns zust\u00e4ndige Aufsichtsbeh\u00f6rde:<\/strong><\/p>\n<p>Landesbeauftragte f\u00fcr den Datenschutz des Landes Niedersachsen<br \/>\nPrinzenstra\u00dfe 5<br \/>\n30159 Hannover<\/p>\n<p>Tel: 0511\/120-4599<br \/>\nE-Mail: <a href=\"mailto:poststelle@lfd.niedersachsen.de\" target=\"_blank\" rel=\"noopener\">poststelle@lfd.niedersachsen.de<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1686147074705{margin-top: 50px !important;padding-top: 40px !important;}&#8221;][vc_column][vc_column_text css=&#8221;&#8221;] Einleitung Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7622","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/pages\/7622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/comments?post=7622"}],"version-history":[{"count":10,"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/pages\/7622\/revisions"}],"predecessor-version":[{"id":22838,"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/pages\/7622\/revisions\/22838"}],"wp:attachment":[{"href":"https:\/\/iav-online.de\/en\/wp-json\/wp\/v2\/media?parent=7622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}